{"id":3273,"date":"2021-03-16T04:18:36","date_gmt":"2021-03-16T04:18:36","guid":{"rendered":"http:\/\/source.wpopal.com\/editech\/?page_id=3273"},"modified":"2021-03-16T04:18:36","modified_gmt":"2021-03-16T04:18:36","slug":"dedicated-team","status":"publish","type":"page","link":"https:\/\/riditstack.com\/index.php\/services\/dedicated-team\/","title":{"rendered":"Dedicated Team"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3273\" class=\"elementor elementor-3273\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eeffb64 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eeffb64\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-63a0b9d4\" data-id=\"63a0b9d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d43194a elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"d43194a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7e656d83\" data-id=\"7e656d83\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ef3e564 elementor-nav-menu__align-left elementor-nav-menu--indicator-none elementor-widget elementor-widget-opal-nav-menu\" data-id=\"2ef3e564\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;}\" data-widget_type=\"opal-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <nav data-subMenusMinWidth=\"260\" data-subMenusMaxWidth=\"500\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-dot e--animation-fade\">\n\t\t\t<ul id=\"menu-2-2ef3e564\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6263\"><a href=\"https:\/\/riditstack.com\/index.php\/projects\/source-to-pay\/\" class=\"elementor-item\">Source-to-Pay<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6264\"><a href=\"https:\/\/riditstack.com\/index.php\/projects\/procuretopay\/\" class=\"elementor-item\">Procure-to-Pay<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6299\"><a href=\"https:\/\/riditstack.com\/index.php\/projects\/supplychain-ai\/\" class=\"elementor-item\">SupplyChain.Ai<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6540\"><a href=\"https:\/\/riditstack.com\/index.php\/projects\/asset-management\/\" class=\"elementor-item\">Asset-Management<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6641\"><a href=\"https:\/\/riditstack.com\/index.php\/projects\/for-sap-customers\/\" class=\"elementor-item\">For SAP Customers<\/a><\/li>\n<\/ul>        <\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3b35e46a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b35e46a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-43dc571b\" data-id=\"43dc571b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a69c7f3 elementor-position-below elementor-widget elementor-widget-heading\" data-id=\"7a69c7f3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 26-02-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><div class=\"elementor-heading-wrapper\" ><div class=\"elementor-heading-wrapper-inner\"><h2 class=\"elementor-heading-title elementor-size-default\">Brouchers\n<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71024998 elementor-position-left elementor-view-default elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"71024998\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/riditstack.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">        <div class=\"elementor-icon-box-wrapper\">\n                            <div class=\"elementor-icon-box-icon\">\n                    <a class=\"elementor-icon elementor-animation-\" href=\"#\">\n                        <i class=\"opal-icon-download\" aria-hidden=\"true\"><\/i>\n                    <\/a>\n                <\/div>\n            \n            <div class=\"elementor-icon-box-content\">\n                <div class=\"elementor-icon-header\">\n                                        <div class=\"elementor-icon-header-inner\">\n                        \n                        <h6 class=\"elementor-icon-box-title\">\n                            <a href=\"#\">\n                                Download Our Brochures                            <\/a>\n                        <\/h6>\n                    <\/div>\n                <\/div>\n                                    <p class=\"elementor-icon-box-description\"><a herf=\"#\">DOWNLOAD <\/a><\/p>\n                             <\/div>\n                    <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47d52832 elementor-position-left elementor-view-default elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"47d52832\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"elementor-icon-box-wrapper\">\n                            <div class=\"elementor-icon-box-icon\">\n                    <a class=\"elementor-icon elementor-animation-\" href=\"#\">\n                        <i class=\"opal-icon-iso-certificates\" aria-hidden=\"true\"><\/i>\n                    <\/a>\n                <\/div>\n            \n            <div class=\"elementor-icon-box-content\">\n                <div class=\"elementor-icon-header\">\n                                        <div class=\"elementor-icon-header-inner\">\n                        \n                        <h6 class=\"elementor-icon-box-title\">\n                            <a href=\"#\">\n                                Our ISO Certificates                            <\/a>\n                        <\/h6>\n                    <\/div>\n                <\/div>\n                                    <p class=\"elementor-icon-box-description\"><a herf=\"#\">DOWNLOAD <\/a><\/p>\n                             <\/div>\n                    <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4f2ba79f elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"4f2ba79f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7d734315\" data-id=\"7d734315\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21f612a8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"21f612a8\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 26-02-2024 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:right;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:left;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-framed\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/riditstack.com\/wp-content\/uploads\/2021\/03\/team07-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-2504\" alt=\"\" srcset=\"https:\/\/riditstack.com\/wp-content\/uploads\/2021\/03\/team07-150x150.jpg 150w, https:\/\/riditstack.com\/wp-content\/uploads\/2021\/03\/team07-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/figure><\/div><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">How Can We Help?<\/h3><p class=\"elementor-image-box-description\"> +1800 - 123 456 78<br\/>\nMail: info@example.com<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-794cf0ea elementor-shape-circle elementor-social-custom elementor-widget elementor-widget-social-icons\" data-id=\"794cf0ea\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 26-02-2024 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em));height:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:inline-flex;background-color:#69727d;align-items:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#69727d}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper\">\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook\" href=\"\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t<i class=\"fa fa-facebook\"><\/i>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter\" href=\"\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t<i class=\"fa fa-twitter\"><\/i>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram\" href=\"\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t<i class=\"fa fa-instagram\"><\/i>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin\" href=\"\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t<i class=\"fa fa-linkedin\"><\/i>\n\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-28a6d227\" data-id=\"28a6d227\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e909c4 elementor-widget elementor-widget-image\" data-id=\"3e909c4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 26-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1290\" height=\"550\" src=\"https:\/\/riditstack.com\/wp-content\/uploads\/2021\/02\/project-2.jpg\" class=\"attachment-full size-full wp-image-1109\" alt=\"\" srcset=\"https:\/\/riditstack.com\/wp-content\/uploads\/2021\/02\/project-2.jpg 1290w, https:\/\/riditstack.com\/wp-content\/uploads\/2021\/02\/project-2-300x128.jpg 300w, https:\/\/riditstack.com\/wp-content\/uploads\/2021\/02\/project-2-1024x437.jpg 1024w, https:\/\/riditstack.com\/wp-content\/uploads\/2021\/02\/project-2-768x327.jpg 768w, https:\/\/riditstack.com\/wp-content\/uploads\/2021\/02\/project-2-700x298.jpg 700w\" sizes=\"(max-width: 1290px) 100vw, 1290px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-864a490 elementor-position-below elementor-widget elementor-widget-heading\" data-id=\"864a490\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-wrapper\" ><div class=\"elementor-heading-wrapper-inner\"><h2 class=\"elementor-heading-title elementor-size-default\">Desktop Computing<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7de65f8e elementor-widget elementor-widget-text-editor\" data-id=\"7de65f8e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 26-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>        <div class=\"elementor-text-editor elementor-clearfix\"><p>Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum.<\/p><p>Duis aute irure dolor in reprehenderit in voluptate velit esse cillur incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamcm dolore eu fugiat nulla pariatur.<\/p><\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-28ad1fb3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28ad1fb3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3f2d2124\" data-id=\"3f2d2124\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3efc3f63 elementor-widget elementor-widget-icon-list\" data-id=\"3efc3f63\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/riditstack.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">        <ul class=\"elementor-icon-list-items\">\n                            <li class=\"elementor-icon-list-item\" >\n                                            <span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-check-circle\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/span>\n                                        <span class=\"elementor-icon-list-text\">Cost of supplies and equipment point<\/span>\n                                    <\/li>\n                            <li class=\"elementor-icon-list-item\" >\n                                            <span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-check-circle\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/span>\n                                        <span class=\"elementor-icon-list-text\">Change the volume of expected of contact<\/span>\n                                    <\/li>\n                            <li class=\"elementor-icon-list-item\" >\n                                            <span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-check-circle\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/span>\n                                        <span class=\"elementor-icon-list-text\">Bibend auctor nisi elit volume are so beguiled<\/span>\n                                    <\/li>\n                    <\/ul>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7c643c6c\" data-id=\"7c643c6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27b2b501 elementor-widget elementor-widget-icon-list\" data-id=\"27b2b501\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <ul class=\"elementor-icon-list-items\">\n                            <li class=\"elementor-icon-list-item\" >\n                                            <span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-check-circle\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/span>\n                                        <span class=\"elementor-icon-list-text\">Bibend auctor nisi elit volume are so beguiled<\/span>\n                                    <\/li>\n                            <li class=\"elementor-icon-list-item\" >\n                                            <span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-check-circle\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/span>\n                                        <span class=\"elementor-icon-list-text\">Change the volume of expected of contact<\/span>\n                                    <\/li>\n                            <li class=\"elementor-icon-list-item\" >\n                                            <span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i class=\"fa fa-check-circle\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/span>\n                                        <span class=\"elementor-icon-list-text\">Cost of supplies and equipment<\/span>\n                                    <\/li>\n                    <\/ul>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-18a23c28 elementor-position-below elementor-widget elementor-widget-heading\" data-id=\"18a23c28\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-wrapper\" ><div class=\"elementor-heading-wrapper-inner\"><h2 class=\"elementor-heading-title elementor-size-default\">Benefits With Our Service<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-146a1a75 elementor-widget elementor-widget-text-editor\" data-id=\"146a1a75\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"elementor-text-editor elementor-clearfix\"><p>They are highly trained for quickly response and provide great service to our customers. Experts are give profitability and success of our business growth &amp; marketing. Network solutions\u2019 to Windows and open source operating systems, as those software platforms gained networking capabilities.<\/p><\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ffbd3b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ffbd3b4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4f76c361\" data-id=\"4f76c361\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ef362d0 elementor-widget elementor-widget-image\" data-id=\"4ef362d0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"410\" height=\"230\" src=\"https:\/\/riditstack.com\/wp-content\/uploads\/2021\/03\/service-banner1.jpg\" class=\"attachment-full size-full wp-image-2641\" alt=\"\" srcset=\"https:\/\/riditstack.com\/wp-content\/uploads\/2021\/03\/service-banner1.jpg 410w, https:\/\/riditstack.com\/wp-content\/uploads\/2021\/03\/service-banner1-300x168.jpg 300w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3d3c31a4\" data-id=\"3d3c31a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cd8a0a8 elementor-widget elementor-widget-image\" data-id=\"7cd8a0a8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"230\" src=\"https:\/\/riditstack.com\/wp-content\/uploads\/2021\/03\/service-banner2.jpg\" class=\"attachment-full size-full wp-image-2642\" alt=\"\" srcset=\"https:\/\/riditstack.com\/wp-content\/uploads\/2021\/03\/service-banner2.jpg 410w, https:\/\/riditstack.com\/wp-content\/uploads\/2021\/03\/service-banner2-300x168.jpg 300w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c6a89a0 elementor-position-below elementor-widget elementor-widget-heading\" data-id=\"3c6a89a0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-wrapper\" ><div class=\"elementor-heading-wrapper-inner\"><h2 class=\"elementor-heading-title elementor-size-default\">Analyzing IT services<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7357d80d elementor-widget elementor-widget-text-editor\" data-id=\"7357d80d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"elementor-text-editor elementor-clearfix\"><p>Lorem Ipsum is simply dummy text of the printing and typesetting industry. Lorem Ipsum has been the industry\u2019s standard dummy text ever since the 1500s, when an unknown printer took a galley of type and scrambled it to make a type specimen book. It has survived not only five centuries,<\/p><\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7368dcd elementor-widget elementor-widget-toggle\" data-id=\"7368dcd\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 26-02-2024 *\/\n.elementor-toggle{text-align:left}.elementor-toggle .elementor-tab-title{font-weight:700;line-height:1;margin:0;padding:15px;border-bottom:1px solid #d5d8dc;cursor:pointer;outline:none}.elementor-toggle .elementor-tab-title .elementor-toggle-icon{display:inline-block;width:1em}.elementor-toggle .elementor-tab-title .elementor-toggle-icon svg{margin-inline-start:-5px;width:1em;height:1em}.elementor-toggle .elementor-tab-title .elementor-toggle-icon.elementor-toggle-icon-right{float:right;text-align:right}.elementor-toggle .elementor-tab-title .elementor-toggle-icon.elementor-toggle-icon-left{float:left;text-align:left}.elementor-toggle .elementor-tab-title .elementor-toggle-icon .elementor-toggle-icon-closed{display:block}.elementor-toggle .elementor-tab-title .elementor-toggle-icon .elementor-toggle-icon-opened{display:none}.elementor-toggle .elementor-tab-title.elementor-active{border-bottom:none}.elementor-toggle .elementor-tab-title.elementor-active .elementor-toggle-icon-closed{display:none}.elementor-toggle .elementor-tab-title.elementor-active .elementor-toggle-icon-opened{display:block}.elementor-toggle .elementor-tab-content{padding:15px;border-bottom:1px solid #d5d8dc;display:none}@media (max-width:767px){.elementor-toggle .elementor-tab-title{padding:12px}.elementor-toggle .elementor-tab-content{padding:12px 10px}}.e-con-inner>.elementor-widget-toggle,.e-con>.elementor-widget-toggle{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>        <div class=\"elementor-toggle\" role=\"tablist\">\n            \n                <div class=\"elementor-toggle-item\">\n                    <div id=\"elementor-tab-title-1211\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-1211\">\n                                                    <span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n                                                                    <span class=\"elementor-toggle-icon-closed\"><i class=\"opal-icon- opal-icon-plus\"><\/i><\/span>\n                                    <span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n                                                            <\/span>\n                        \n                        <a href=\"\" class=\"elementor-toggle-title\">01. When do I need an Interior Designer?<\/a>\n                    <\/div>\n\n                    <div id=\"elementor-tab-content-1211\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1211\"><p>Solution Analysts welcomes you to try our services. We invest the same time and energy in Pilot Projects as real projects. We have always succeeded in continuing the relationship after demonstration of ability in a pilot project different from prototypes.<\/p><\/div>\n                <\/div>\n            \n                <div class=\"elementor-toggle-item\">\n                    <div id=\"elementor-tab-title-1212\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"tab\" aria-controls=\"elementor-tab-content-1212\">\n                                                    <span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n                                                                    <span class=\"elementor-toggle-icon-closed\"><i class=\"opal-icon- opal-icon-plus\"><\/i><\/span>\n                                    <span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n                                                            <\/span>\n                        \n                        <a href=\"\" class=\"elementor-toggle-title\">02. Why do you have a design fee and purchasing fee on the product?<\/a>\n                    <\/div>\n\n                    <div id=\"elementor-tab-content-1212\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1212\"><p>Solution Analysts welcomes you to try our services. We invest the same time and energy in Pilot Projects as real projects. We have always succeeded in continuing the relationship after demonstration of ability in a pilot project different from prototypes.<\/p><\/div>\n                <\/div>\n            \n                <div class=\"elementor-toggle-item\">\n                    <div id=\"elementor-tab-title-1213\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"tab\" aria-controls=\"elementor-tab-content-1213\">\n                                                    <span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n                                                                    <span class=\"elementor-toggle-icon-closed\"><i class=\"opal-icon- opal-icon-plus\"><\/i><\/span>\n                                    <span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n                                                            <\/span>\n                        \n                        <a href=\"\" class=\"elementor-toggle-title\">03. What should I have at our first meeting for my project?<\/a>\n                    <\/div>\n\n                    <div id=\"elementor-tab-content-1213\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1213\"><p>Solution Analysts welcomes you to try our services. We invest the same time and energy in Pilot Projects as real projects. We have always succeeded in continuing the relationship after demonstration of ability in a pilot project different from prototypes.<\/p><\/div>\n                <\/div>\n                    <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":617,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-elementor.php","meta":{"inline_featured_image":false,"footnotes":""},"_links":{"self":[{"href":"https:\/\/riditstack.com\/index.php\/wp-json\/wp\/v2\/pages\/3273"}],"collection":[{"href":"https:\/\/riditstack.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/riditstack.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/riditstack.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/riditstack.com\/index.php\/wp-json\/wp\/v2\/comments?post=3273"}],"version-history":[{"count":0,"href":"https:\/\/riditstack.com\/index.php\/wp-json\/wp\/v2\/pages\/3273\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/riditstack.com\/index.php\/wp-json\/wp\/v2\/pages\/617"}],"wp:attachment":[{"href":"https:\/\/riditstack.com\/index.php\/wp-json\/wp\/v2\/media?parent=3273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}